{"id":13306,"date":"2017-09-13T12:26:25","date_gmt":"2017-09-13T17:26:25","guid":{"rendered":"http:\/\/radionoticiascasanare.com\/inicio\/?p=13306"},"modified":"2017-09-13T12:26:25","modified_gmt":"2017-09-13T17:26:25","slug":"boletas-para-futbol-a-cambio-de-firmas-por-vargas-lleras","status":"publish","type":"post","link":"https:\/\/radionoticiascasanare.com\/inicio\/boletas-para-futbol-a-cambio-de-firmas-por-vargas-lleras\/","title":{"rendered":"Boletas para f\u00fatbol a cambio de firmas por Vargas Lleras"},"content":{"rendered":"<figure id=\"attachment_13307\" aria-describedby=\"caption-attachment-13307\" style=\"width: 299px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-13307\" src=\"http:\/\/radionoticiascasanare.com\/inicio\/wp-content\/uploads\/2017\/09\/vargaslleras-archivo2_1.png\" alt=\"\" width=\"299\" height=\"199\" \/><figcaption id=\"caption-attachment-13307\" class=\"wp-caption-text\">ElEspectador.com<\/figcaption><\/figure>\n<p>Una nueva pol\u00e9mica surgi\u00f3 en torno a la campa\u00f1a del exvicepresident<a class=\"cvisible-poptrigger\" href=\"http:\/\/www.elespectador.com\/noticias\/politica\/boletas-para-futbol-cambio-de-firmas-por-vargas-lleras-articulo-712994#\">e Germ\u00e1n Vargas Ller<\/a>as. Se trata de <strong>una campa\u00f1a en que la se invita a los j\u00f3venes de Cambio Radical\u00a0a conseguir el mayor n\u00famero de firmas a favor del fundador de la colectividad<\/strong>, a pesar de que hoy busca la candidatura por un movimiento significativo de ciudadanos. <strong>El ganador recibir\u00e1 una boleta para el partido en Barranquilla entre Colombia y Paraguay, un tiquete terrestre y alojamiento<\/strong>.<\/p>\n<p>A los se\u00f1alamientos de que Cambio Radical estar\u00eda impulsando la campa\u00f1a #MejorVargasLleras, respondi\u00f3 en Blu Radio <strong>el actual presidente de la colectividad, Jorge Enrique V\u00e9lez, quien se\u00f1al\u00f3 que esta competencia fue impulsada por las juventudes del partido<\/strong>, que la considera sana y el partido que dirige no ha puesto recursos para dicha iniciativa.<\/p>\n<p><img decoding=\"async\" class=\"alignleft\" src=\"http:\/\/www.elespectador.com\/sites\/default\/files\/boletasvargaslleras.png\" alt=\"\" width=\"303\" height=\"302\" data-picture-mapping=\"main\" \/><\/p>\n<p>\u201cLos j\u00f3venes de Cambio Radical est\u00e1n muy din\u00e1micos. Hemos hechos una reestructuraci\u00f3n y lo hemos separado por regiones.\u00a0 La norte, la centro. Y entre ellos se ha generado su propia competencia. <strong>Ellos tomaron la decisi\u00f3n de hacer una competencia sana de quien consigue m\u00e1s firmas. Han vuelto tambi\u00e9n esto una fiesta<\/strong>. Y se propusieron entre ellos. A la pregunta si lo paga el partido, la respuesta es ustedes creen que nosotros dar\u00edamos un pasaje terrestre, obviamente le dar\u00edamos uno a\u00e9reo. La boleta la consiguen los de la costa, y van a ir a dormir a la casa de los compa\u00f1eros. <strong>Fue un proceso de ellos mismo, nada tiene que ver el Partido<\/strong>\u201d explic\u00f3 el exsuperintendente de Notariado y Registro.<\/p>\n<p>V\u00e9lez tambi\u00e9n consider\u00f3 que se pueden haber equivocado usando los logos de la colectividad, pero que \u201ccomo ellos tienen sus propias im\u00e1genes de juventudes del partido\u201d, \u00e9l no \u201cle vio nada de malo\u201d. Finalmente <strong>dijo que German Vargas Lleras no es el candidato de Cambio Radical y nada tiene que ver con el partido<\/strong>, eso s\u00ed que apoyan el proceso que decida porque el exvicepresidente, porque considera que es \u201cla mejor persona para este pa\u00eds\u201d.<\/p>\n<p>Una respuesta similar dio a la Silla Vac\u00eda <strong>el coordinador de las juventudes de Cambio Radical, Gustavo Moreno, quien aclar\u00f3 que no se entregar\u00e1 una sino cuatro boletas para asistir al partido<\/strong> a quienes recojan el mayor n\u00famero de firmas.\u00a0 \u201cNo le pedimos permiso a nadie, ni nos est\u00e1n apoyando las directivas\u201d, le dijo Moreno a La Silla Vac\u00eda.<\/p>\n<p>Fuente y Fotograf\u00eda ElEspectador.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una nueva pol\u00e9mica surgi\u00f3 en torno a la campa\u00f1a del exvicepresidente Germ\u00e1n Vargas Lleras. Se trata de una campa\u00f1a en que la se invita a los j\u00f3venes de Cambio Radical\u00a0a conseguir el mayor n\u00famero de firmas a favor del fundador de la colectividad, a pesar de que hoy busca la candidatura por un movimiento significativo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51],"tags":[2437,4954,3045,2265,4122,238],"class_list":["post-13306","post","type-post","status-publish","format-standard","hentry","category-nacional","tag-cambio-radical","tag-campana-a-la-presidencia","tag-german-vargas-lleras","tag-nacional","tag-polemica","tag-radio-noticias-casanare"],"_links":{"self":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/posts\/13306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/comments?post=13306"}],"version-history":[{"count":0,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/posts\/13306\/revisions"}],"wp:attachment":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/media?parent=13306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/categories?post=13306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/tags?post=13306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}