{"id":29532,"date":"2020-08-01T08:00:26","date_gmt":"2020-08-01T13:00:26","guid":{"rendered":"https:\/\/radionoticiascasanare.com\/inicio\/?p=29532"},"modified":"2020-08-01T08:00:26","modified_gmt":"2020-08-01T13:00:26","slug":"revelan-que-ninos-pequenos-son-portadores-de-altos-niveles-de-covid-19","status":"publish","type":"post","link":"https:\/\/radionoticiascasanare.com\/inicio\/revelan-que-ninos-pequenos-son-portadores-de-altos-niveles-de-covid-19\/","title":{"rendered":"Revelan que ni\u00f1os peque\u00f1os son portadores de altos niveles de covid-19"},"content":{"rendered":"<figure id=\"attachment_29533\" aria-describedby=\"caption-attachment-29533\" style=\"width: 304px\" class=\"wp-caption alignleft\"><img decoding=\"async\" class=\" wp-image-29533\" src=\"https:\/\/radionoticiascasanare.com\/inicio\/wp-content\/uploads\/2020\/08\/5f237311b6c3c-320x160.jpeg\" alt=\"\" width=\"304\" height=\"152\" \/><figcaption id=\"caption-attachment-29533\" class=\"wp-caption-text\">AFP-eltiempo.com<\/figcaption><\/figure>\n<p><b>Los ni\u00f1os menores de cinco a\u00f1os tienen entre 10 y 100 veces m\u00e1s nivel de material gen\u00e9tico de coronavirus en sus narices que ni\u00f1os m\u00e1s grandes y los adultos,\u00a0<\/b>seg\u00fan un estudio en Jama Pediatrics, publicado este jueves.<\/p>\n<p>Los autores indicaron que esto significa que los ni\u00f1os peque\u00f1os podr\u00edan ser importantes conductores de covid-19 en la transmisi\u00f3n entre sus comunidades, una sugerencia que no concuerda con la narrativa actual.<\/p>\n<p>El informe se conoce en momentos en que el gobierno del presidente estadounidense,\u00a0<b>Donald Trump, presiona con fuerza para que las escuelas y guarder\u00edas abran sus puertas para dar un impulso a la econom\u00eda.<br \/>\n<\/b><br \/>\nLos investigadores hicieron entre el 23 de marzo y el 27 de abril\u00a0<b>pruebas de hisopado nasal entre 145 pacientes en Chicago enfermos leves a moderados dentro de la semana de aparici\u00f3n de los s\u00edntomas.<\/b><\/p>\n<p>Los pacientes se dividieron en tres grupos:\u00a0<b>46 ni\u00f1os menores de cinco a\u00f1os, 51 de cinco a 17 a\u00f1os, y 48 adultos de 18 a 65 a\u00f1os.<\/b><\/p>\n<p>El equipo, conducido por el doctor Taylor Heald-Sargent, del Hospital Infantil Ann &amp; Robert H. Lurie, observ\u00f3 &#8220;una cantidad entre 10 y 100 veces mayor de Sars-CoV-2 en el tracto respiratorio superior de los ni\u00f1os peque\u00f1os&#8221;.<\/p>\n<p>Los autores agregaron que un estudio de laboratorio reciente demostr\u00f3 que cuanto m\u00e1s material gen\u00e9tico presente, m\u00e1s virus infecciosos pod\u00edan desarrollarse. Tambi\u00e9n previamente se mostr\u00f3 que los ni\u00f1os con altas cargas virales en el virus sincitial respiratorio (RSV) son m\u00e1s propensos a propagar la enfermedad.<\/p>\n<p>&#8220;<b>Por lo tanto, los ni\u00f1os peque\u00f1os pueden ser potencialmente importantes impulsores de la propagaci\u00f3n del Sars-CoV-2 en la poblaci\u00f3n general<\/b>&#8220;, escribieron los autores.<\/p>\n<p>&#8220;Los h\u00e1bitos de comportamiento de los ni\u00f1os peque\u00f1os y los lugares cerrados en las escuelas y guarder\u00edas suscitan preocupaci\u00f3n por la amplificaci\u00f3n del Sars-CoV-2 en esta poblaci\u00f3n a medida que se flexibilizan las restricciones de salud p\u00fablica&#8221;, concluyeron.<\/p>\n<p>Los nuevos hallazgos contradicen la opini\u00f3n actual de las autoridades de salud de que los ni\u00f1os peque\u00f1os, que seg\u00fan se estableci\u00f3 tienen muchas menos probabilidades de enfermarse gravemente de covid-19, no son importantes vectores de contagio.\u00a0<b>Sin embargo, hasta ahora se ha investigado bastante poco sobre el tema.<\/b><\/p>\n<p>Un estudio reciente en Corea del Sur encontr\u00f3 que las personas entre 10 y 19 a\u00f1os transmiten el covid-19 dentro de las casas tanto como los adultos, pero los menores de nueve a\u00f1os trasmiten el virus en tasas m\u00e1s bajas.<\/p>\n<p>Fuente y Fotograf\u00eda eltiempo.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los ni\u00f1os menores de cinco a\u00f1os tienen entre 10 y 100 veces m\u00e1s nivel de material gen\u00e9tico de coronavirus en sus narices que ni\u00f1os m\u00e1s grandes y los adultos,\u00a0seg\u00fan un estudio en Jama Pediatrics, publicado este jueves. Los autores indicaron que esto significa que los ni\u00f1os peque\u00f1os podr\u00edan ser importantes conductores de covid-19 en la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85,2280],"tags":[10868,11029,654,12149,12150,6,11035,12151,238],"class_list":["post-29532","post","type-post","status-publish","format-standard","hentry","category-internacional","category-salud","tag-coronavirus","tag-covid19","tag-internacional","tag-mas-carga","tag-menores-de-5-anos","tag-ninos","tag-pandemia","tag-portadores","tag-radio-noticias-casanare"],"_links":{"self":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/posts\/29532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/comments?post=29532"}],"version-history":[{"count":0,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/posts\/29532\/revisions"}],"wp:attachment":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/media?parent=29532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/categories?post=29532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/tags?post=29532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}