{"id":33824,"date":"2021-04-09T07:54:23","date_gmt":"2021-04-09T12:54:23","guid":{"rendered":"https:\/\/radionoticiascasanare.com\/inicio\/?p=33824"},"modified":"2021-04-09T07:54:23","modified_gmt":"2021-04-09T12:54:23","slug":"extranjeros-sin-prueba-pcr-negativa-no-podran-ingresar-al-pais","status":"publish","type":"post","link":"https:\/\/radionoticiascasanare.com\/inicio\/extranjeros-sin-prueba-pcr-negativa-no-podran-ingresar-al-pais\/","title":{"rendered":"Extranjeros sin prueba PCR negativa no podr\u00e1n ingresar al pa\u00eds"},"content":{"rendered":"<figure id=\"attachment_33825\" aria-describedby=\"caption-attachment-33825\" style=\"width: 311px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-33825\" src=\"https:\/\/radionoticiascasanare.com\/inicio\/wp-content\/uploads\/2021\/04\/puebas-covid-1-311x192.jpg\" alt=\"\" width=\"311\" height=\"192\" \/><figcaption id=\"caption-attachment-33825\" class=\"wp-caption-text\">elnuevosiglo.com<\/figcaption><\/figure>\n<p>El director de Migraci\u00f3n Colombia, Juan Francisco Espinosa, ratific\u00f3 que cualquier extranjero que pretenda<strong>\u00a0ingresar a Colombia tiene que traer una prueba PCR negativa<\/strong>.<\/p>\n<p>Adicionalmente dijo que en las \u00faltimas horas se hicieron\u00a0<strong>10 inadmisiones en el Aeropuerto El Dorado y 11 en Cartagena<\/strong>, por el cumplimiento de la norma.<\/p>\n<p>\u201cEn cuanto a los colombianos y extranjeros residentes en el pa\u00eds, tienen que hacerse la prueba PCR negativa pero, si no es posible, tendr\u00e1n que hacer un\u00a0<strong>aislamiento obligatorio durante 14 d\u00edas<\/strong>\u00a0en donde vivan. Y si pretenden salir del aislamiento, tendr\u00e1n que hacerse una prueba PCR negativa\u201d, explic\u00f3.<\/p>\n<p>Fuente y Fotograf\u00eda Elnuevosiglo.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El director de Migraci\u00f3n Colombia, Juan Francisco Espinosa, ratific\u00f3 que cualquier extranjero que pretenda\u00a0ingresar a Colombia tiene que traer una prueba PCR negativa. Adicionalmente dijo que en las \u00faltimas horas se hicieron\u00a010 inadmisiones en el Aeropuerto El Dorado y 11 en Cartagena, por el cumplimiento de la norma. \u201cEn cuanto a los colombianos y extranjeros [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[168,85,2280],"tags":[13073,13711,654,13712,13713,238],"class_list":["post-33824","post","type-post","status-publish","format-standard","hentry","category-generales","category-internacional","category-salud","tag-extranjeros","tag-ingreso-al-pais","tag-internacional","tag-negativas","tag-pruebas-pcr","tag-radio-noticias-casanare"],"_links":{"self":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/posts\/33824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/comments?post=33824"}],"version-history":[{"count":0,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/posts\/33824\/revisions"}],"wp:attachment":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/media?parent=33824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/categories?post=33824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/tags?post=33824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}