{"id":40483,"date":"2022-04-11T06:29:17","date_gmt":"2022-04-11T11:29:17","guid":{"rendered":"https:\/\/radionoticiascasanare.com\/inicio\/?p=40483"},"modified":"2022-04-11T06:29:17","modified_gmt":"2022-04-11T11:29:17","slug":"programese-esta-semana-santa-con-los-planes-que-la-administracion-municipal-tiene-para-usted","status":"publish","type":"post","link":"https:\/\/radionoticiascasanare.com\/inicio\/programese-esta-semana-santa-con-los-planes-que-la-administracion-municipal-tiene-para-usted\/","title":{"rendered":"Progr\u00e1mese esta semana santa con los planes que la administraci\u00f3n municipal tiene para usted"},"content":{"rendered":"<p style=\"font-weight: 400;\"><img decoding=\"async\" class=\"wp-image-40490 alignleft\" src=\"https:\/\/radionoticiascasanare.com\/inicio\/wp-content\/uploads\/2022\/04\/yopal-143x192.png\" alt=\"\" width=\"166\" height=\"223\" \/>El Instituto de Cultura y Turismo de Yopal (ICTY) ofrece una completa programaci\u00f3n art\u00edstica y cultural, encabezada por el Campeonato Nacional de la Hayaca, adem\u00e1s de diversas actividades para propios y visitantes; as\u00ed lo anunci\u00f3 la Directora Sof\u00eda Rodr\u00edguez M\u00fanera.<\/p>\n<p style=\"font-weight: 400;\">\u201cA todos los invito a disfrutar esta Semana Santa en Yopal. Tenemos un patrimonio \u00fanico y un potencial tur\u00edstico que har\u00e1 que se enamoren y se sorprendan en el coraz\u00f3n del llano. As\u00ed que no pueden perderse todas las actividades que esta Administraci\u00f3n Municipal, en cabeza del alcalde Luis Eduardo Castro, ha preparado para que todos disfruten en familia y amigos durante la\u00a0temporada de tradici\u00f3n religiosa\u201d, se\u00f1al\u00f3 Rodr\u00edguez M\u00fanera.<\/p>\n<p style=\"font-weight: 400;\">Uno de los principales atractivos de la Semana Mayor ser\u00e1 el Campeonato Nacional de la Hayaca de Unicentro Yopal, el cual incluye una programaci\u00f3n llena de tradici\u00f3n, cultura y gastronom\u00eda alrededor de este plato t\u00edpico llanero, con participantes de diferentes lugares de la Orinoquia. El Festival inici\u00f3 con la Eucar\u00edstia del Domingo de Ramos, y se prolongar\u00e1 hasta el pr\u00f3ximo 16 de abril, incluyendo muestras art\u00edsticas en la Casa Museo Ocho de Julio, juegos tradicionales y concursos.<\/p>\n<p>Estos son algunos de los eventos programados:<\/p>\n<p style=\"font-weight: 400;\"><strong>Feria de Gastronom\u00eda, Dise\u00f1o, Artesan\u00eda y Plantas<\/strong><\/p>\n<p style=\"font-weight: 400;\">Un punto de encuentro para emprendedores, cocineros, productores, artistas y dise\u00f1adores para crear sinergias creativas en diversas propuestas.<\/p>\n<p style=\"font-weight: 400;\">Fecha: Lunes 11 y Martes 12 de ABRIL<\/p>\n<p style=\"font-weight: 400;\">Hora: Desde las 8:00AM<\/p>\n<p style=\"font-weight: 400;\">Lugar: Casa Museo Ocho de Julio Crr. 20 #7 \u2013 02<\/p>\n<p style=\"font-weight: 400;\"><strong>Cine Foro<\/strong><\/p>\n<p style=\"font-weight: 400;\">Sum\u00e9rgete en el s\u00e9ptimo arte, a trav\u00e9s de un di\u00e1logo entre el espectador y la obra.<\/p>\n<p style=\"font-weight: 400;\">Lunes 11 ABRIL \/ 6:00PM \/ Pel\u00edcula: 4 golondrinas no hacen llover \/ Casa Museo Ocho de Julio<\/p>\n<p style=\"font-weight: 400;\">Martes 12 ABRIL \/ 6:00PM \/ Cortometraje: Fundo \/ Casa Museo Ocho de Julio<\/p>\n<p style=\"font-weight: 400;\"><strong>Tarde de Tertulia (presencial\/virtual)<\/strong><\/p>\n<p style=\"font-weight: 400;\">Una conversaci\u00f3n sobre los mitos y leyendas del llano, a cargo del portador de Cantos de Trabajo de Llano, Dar\u00edo Salas.<\/p>\n<p style=\"font-weight: 400;\">11 ABRIL \/ 4:00PM \/ Casa Museo Ocho de Julio<\/p>\n<p style=\"font-weight: 400;\"><strong>Joropo en vivo<\/strong><\/p>\n<p style=\"font-weight: 400;\">En Semana Santa vibra con el baile llanero en las modalidades criollo y moderno.<\/p>\n<p style=\"font-weight: 400;\">Lunes 11 ABRIL \/ 10:00PM \/ Casa Museo Ocho de Julio<\/p>\n<p style=\"font-weight: 400;\"><strong>Inauguraci\u00f3n Exposici\u00f3n Asiduidad Llanera<\/strong><\/p>\n<p style=\"font-weight: 400;\">Artistas: Aldemar Mattar, Salvador Cantor, Diego Garc\u00eda, Cesar Rinc\u00f3n, Ferney Casta\u00f1eda, Rossy Valero, Jaime Garc\u00eda, Jimmy Avenda\u00f1o, Salom\u00f3n Urrea y Jhon Blanco.<\/p>\n<p style=\"font-weight: 400;\">Lunes 11 ABRIL \/ 9:00AM \/ Casa Museo Ocho de Julio<\/p>\n<p style=\"font-weight: 400;\"><strong>Homenaje a leyendas de la m\u00fasica llanera<\/strong><\/p>\n<p style=\"font-weight: 400;\">Tributo a los cantantes Lorgio Rodr\u00edguez, Tirso Delgado y Orlando Vega<\/p>\n<p style=\"font-weight: 400;\">Martes 12 ABRIL \/ 10:00AM \/ Casa Museo Ocho de Julio.<\/p>\n<p style=\"font-weight: 400;\"><strong>Conversatorio sobre la Virgen de Manare (Presencial\/virtual)<\/strong><\/p>\n<p style=\"font-weight: 400;\">La escritora Pilar Le\u00f3n nos contar\u00e1 la historia de la Virgen de Manare, las penurias que vivi\u00f3 y las festividades que se celebran en torno a esta advocaci\u00f3n de la virgen Mar\u00eda.<\/p>\n<p style=\"font-weight: 400;\">Mates 12 ABRIL \/ 4:00PM \/ Casa Museo Ocho de Julio<\/p>\n<p style=\"font-weight: 400;\"><strong>Joropo en el Aeropuerto El Alcarav\u00e1n<\/strong><\/p>\n<p>Al ritmo del folclor llanero, recibimos a los visitantes de Yopal: Coraz\u00f3n del Llano<\/p>\n<p>Lunes 11, martes 12, mi\u00e9rcoles 13 de abril \/ Aeropuerto Internacional El Alcarav\u00e1n.<\/p>\n<p style=\"font-weight: 400;\"><strong>Atardecer Cultural<\/strong><\/p>\n<p style=\"font-weight: 400;\">El Campeonato Nacional de la Hayaca ser\u00e1 el escenario para las presentaciones art\u00edsticas durante la Semana Mayor, con decenas de artistas invitados.<\/p>\n<p style=\"font-weight: 400;\">Mi\u00e9rcoles 13, jueves 14, viernes 15 (m\u00fasica g\u00f3spel) y s\u00e1bado 16 ABRIL \/ 4:00PM \/ Unicentro Yopal.<\/p>\n<p style=\"font-weight: 400;\"><strong>Viacrusis por la Reconciliaci\u00f3n<\/strong><\/p>\n<p style=\"font-weight: 400;\">Viernes 15 ABRIL \/ 6:00AM \/ Parque La Iguana<\/p>\n<p>Fuente y Fotograf\u00eda Alcald\u00eda de Yopal<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto de Cultura y Turismo de Yopal (ICTY) ofrece una completa programaci\u00f3n art\u00edstica y cultural, encabezada por el Campeonato Nacional de la Hayaca, adem\u00e1s de diversas actividades para propios y visitantes; as\u00ed lo anunci\u00f3 la Directora Sof\u00eda Rodr\u00edguez M\u00fanera. \u201cA todos los invito a disfrutar esta Semana Santa en Yopal. Tenemos un patrimonio \u00fanico [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,66,8492,8493,132,9680],"tags":[237,3,16539,238,388,16],"class_list":["post-40483","post","type-post","status-publish","format-standard","hentry","category-casanare","category-destacadas","category-noticias-casanare","category-noticias-de-casanare","category-orinoquia","category-region","tag-alcaldia-de-yopal","tag-casanare","tag-programacion-cultural","tag-radio-noticias-casanare","tag-semana-santa","tag-yopal"],"_links":{"self":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/posts\/40483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/comments?post=40483"}],"version-history":[{"count":0,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/posts\/40483\/revisions"}],"wp:attachment":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/media?parent=40483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/categories?post=40483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/tags?post=40483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}