{"id":43417,"date":"2022-10-07T07:52:12","date_gmt":"2022-10-07T12:52:12","guid":{"rendered":"https:\/\/radionoticiascasanare.com\/inicio\/?p=43417"},"modified":"2022-10-07T07:52:12","modified_gmt":"2022-10-07T12:52:12","slug":"ecopetrol-y-comunidades-de-yopal-trabajan-para-recuperar-mas-de-80-hectareas-de-bosque","status":"publish","type":"post","link":"https:\/\/radionoticiascasanare.com\/inicio\/ecopetrol-y-comunidades-de-yopal-trabajan-para-recuperar-mas-de-80-hectareas-de-bosque\/","title":{"rendered":"Ecopetrol y comunidades de Yopal trabajan para recuperar m\u00e1s de 80 hect\u00e1reas de bosque"},"content":{"rendered":"<p style=\"font-weight: 400;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-43420 alignleft\" src=\"https:\/\/radionoticiascasanare.com\/inicio\/wp-content\/uploads\/2022\/10\/Proyecto-Reviva-La-Primavera-de-Ecopetrol-11-288x192.jpg\" alt=\"\" width=\"288\" height=\"192\" \/>Ecopetrol, en articulaci\u00f3n con la comunidad y en alianza con ABC Colombia, Somos territorio, realiza restauraci\u00f3n ecol\u00f3gica en m\u00e1s de 80 hect\u00e1reas de bosque en el municipio de Yopal, a trav\u00e9s del proyecto \u2018Reviva La Primavera\u2019.<\/p>\n<p style=\"font-weight: 400;\">Se\u00a0busca\u00a0recuperar la conectividad de \u00e1reas boscosas y afianzar la relaci\u00f3n entre las comunidades y el medio ambiente mediante el reconocimiento del territorio, la biodiversidad de fauna y flora existente, sus ecosistemas y la importancia de \u00e9stos en la protecci\u00f3n del agua.<\/p>\n<p style=\"font-weight: 400;\">Esta iniciativa hace parte del programa de compensaciones del medio bi\u00f3tico para el proyecto Pauto M, aprobado por la Autoridad Nacional de Licencias Ambientales (ANLA), desde el a\u00f1o 2015, que ha permitido generar oportunidades laborales para la comunidad, entre las que se destaca que el 45% del personal vinculado son mujeres cabeza de hogar.<\/p>\n<p style=\"font-weight: 400;\">\u201cAl recuperar los bosques, directamente estamos recuperando y protegiendo los cuerpos de agua y los nacederos. Es as\u00ed como Ecopetrol le apunta no s\u00f3lo al cumplimiento legal ambiental sino a la recuperaci\u00f3n de ecosistemas y a la educaci\u00f3n ambiental con la participaci\u00f3n de comunidad, trabajando en armon\u00eda con el medio ambiente\u201d, manifest\u00f3 Mar\u00eda Argenis Avilez Trujillo, Profesional del Departamento Ambiental de la Regional Piedemonte de Ecopetrol.<\/p>\n<p style=\"font-weight: 400;\">Por su parte, Pedro Emilio Mart\u00ednez, coordinador del proyecto en ABC Colombia, cuenta c\u00f3mo adem\u00e1s de restaurar los servicios ecosist\u00e9micos, las comunidades han reconocido la importancia del bosque nativo para la protecci\u00f3n de los suelos.<\/p>\n<p style=\"font-weight: 400;\">\u201cImportante ac\u00e1 resaltar el compromiso y la apropiaci\u00f3n de la comunidad. Le dimos la importancia a las plantas nativas, a los saberes de la gente para conservar su flora y su fauna. Hemos formado los guardabosques y viveristas con conocimientos t\u00e9cnicos, pero ellos, a su vez nos han aportado su conocimiento\u201d, resalt\u00f3 el profesional forestal.<\/p>\n<p style=\"font-weight: 400;\">Desde el inicio de las operaciones de los campos Pauto y Flore\u00f1a, Ecopetrol ha invertido en este proyecto m\u00e1s de\u00a0$828 millones:\u00a0en el a\u00f1o 2020 aport\u00f3 $158 millones, en el 2021 cerca de $385 millones y 285 millones ejecutados a septiembre de 2022 que han permitido sembrar m\u00e1s de 5.500 \u00e1rboles de 36 especies nativas y se han formado alrededor de 25 personas como viveristas, guardabosques y obreros forestales de las veredas de\u00a0Rinc\u00f3n del Soldado, La Colorada y La Esperanza.<\/p>\n<p style=\"font-weight: 400;\">Derly Fern\u00e1ndez, quien se desempe\u00f1a como guardabosques, destaca los cambios significativos en el paisaje con el desarrollo de las actividades de reforestaci\u00f3n y protecci\u00f3n.<\/p>\n<p style=\"font-weight: 400;\">\u201cHemos visto cambios en el clima, reforestaci\u00f3n de plantas nativas y durante las rondas que realizo he encontrado huellas de cachicamos, de lapas, de venados, de cafuches y vegetaci\u00f3n\u201d, manifest\u00f3.<\/p>\n<p style=\"font-weight: 400;\">A trav\u00e9s del proyecto se desarrollan actividades de\u00a0monitoreo socioambiental, an\u00e1lisis de cobertura de restauraci\u00f3n ecol\u00f3gica, mantenimientos, siembra, resiembra o enriquecimiento de \u00e1rboles, barreras contrafuegos y una estrategia social, en la cual, ni\u00f1os, mujeres y familias desarrollan actividades de educaci\u00f3n ambiental y pr\u00e1cticas de agricultura comunitaria (huertas escolares y caseras), con el prop\u00f3sito de generar en ellos, valores de conservaci\u00f3n.<\/p>\n<p style=\"font-weight: 400;\">\u201cHemos aprendido qu\u00e9 es la germinaci\u00f3n, a cuidar el medio ambiente y a no botar basura, en la huerta escolar hemos sembramos pepino, lechuga, cilantro, tomate, albahaca, ruda, hierba buena y todo eso lo vamos a utilizar para consumir en el almuerzo, para que nos puedan preparar algo rico con eso\u201d, cuenta Eduardo Tique, estudiante de la instituci\u00f3n educativa Juan Jos\u00e9 Rond\u00f3n.<\/p>\n<p style=\"font-weight: 400;\">\u2018Reviva La Primavera\u2019 hace parte de las iniciativas de recuperaci\u00f3n ambiental, que Ecopetrol realiza en las \u00e1reas de influencia de sus operaciones en el municipio de Yopal, entre las cuales tambi\u00e9n se destacan los Acuerdos de Conservaci\u00f3n Producci\u00f3n y los Acuerdos de Conservaci\u00f3n Voluntarios que generan beneficios en los suelos, mayor conectividad, biodiversidad y protecci\u00f3n del recurso h\u00eddrico en los ecosistemas del Piedemonte.<\/p>\n<p>Fuente y Fotograf\u00eda Ecopetrol<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ecopetrol, en articulaci\u00f3n con la comunidad y en alianza con ABC Colombia, Somos territorio, realiza restauraci\u00f3n ecol\u00f3gica en m\u00e1s de 80 hect\u00e1reas de bosque en el municipio de Yopal, a trav\u00e9s del proyecto \u2018Reviva La Primavera\u2019. Se\u00a0busca\u00a0recuperar la conectividad de \u00e1reas boscosas y afianzar la relaci\u00f3n entre las comunidades y el medio ambiente mediante el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,66,8492,8493,132,9680],"tags":[17817,932,3,120,238,2397,17818,17819,16],"class_list":["post-43417","post","type-post","status-publish","format-standard","hentry","category-casanare","category-destacadas","category-noticias-casanare","category-noticias-de-casanare","category-orinoquia","category-region","tag-80-hectnareas-de-bosque","tag-anla","tag-casanare","tag-ecopetrol","tag-radio-noticias-casanare","tag-recuperacion","tag-restauracion-ecologica","tag-reviva-la-primavera","tag-yopal"],"_links":{"self":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/posts\/43417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/comments?post=43417"}],"version-history":[{"count":0,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/posts\/43417\/revisions"}],"wp:attachment":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/media?parent=43417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/categories?post=43417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/tags?post=43417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}