{"id":5697,"date":"2016-07-11T06:39:58","date_gmt":"2016-07-11T06:39:58","guid":{"rendered":"http:\/\/radionoticiascasanare.com\/inicio\/?p=5697"},"modified":"2016-07-11T06:39:58","modified_gmt":"2016-07-11T06:39:58","slug":"beneficiarios-del-proyectos-senderos-de-manare-esperan-respuestas-en-debate-en-el-concejo-de-yopal","status":"publish","type":"post","link":"https:\/\/radionoticiascasanare.com\/inicio\/beneficiarios-del-proyectos-senderos-de-manare-esperan-respuestas-en-debate-en-el-concejo-de-yopal\/","title":{"rendered":"Beneficiarios del proyecto Senderos de Manare esperan respuestas en debate en el Concejo de Yopal"},"content":{"rendered":"<p>Los graves problemas estructurales del Conjunto Senderos de Manare ser\u00e1n analizados por el Concejo de Yopal, por lo que cit\u00f3 al Gerente de la Inversora Manare, Juan Eduardo Goenaga y al jefe de la Oficina Asesora de Planeaci\u00f3n, Fabio Andr\u00e9s Fajardo Restrepo.<\/p>\n<p>El Presidente de la Corporaci\u00f3n, Fabio Su\u00e1rez Caro indic\u00f3 que el debate se adelanta al conocer una serie de inconformidades, quejas y denuncias que han hecho los beneficiarios, que han revelado en diferentes medios de comunicaci\u00f3n, entre ellos <strong>Radio Noticias Casanare<\/strong>\u00a0como este proyecto de vivienda ha sufrido una serie de retrasos, problemas de construcci\u00f3n y otras situaciones, que han sido evadidas por el responsable de la obra.<\/p>\n<p>&#8220;Hemos tenido testimonios de beneficiarios quienes han manifestado que se presentan dificultades como la falta de zonas verdes, el punto de recolecci\u00f3n de aguas lluvias y negras, alumbrado p\u00fablico y \u00a0tambi\u00e9n la reducci\u00f3n de los senderos peatonales entre otros&#8221;, precis\u00f3 el integrante de la Corporaci\u00f3n.<\/p>\n<p>Su\u00e1rez Caro indic\u00f3 que el representante de Inversora Manare deber\u00e1 responder a las 221 familias. Este conjunto residencial beneficiar\u00e1 \u00a0a 221 familias que buscan soluciones ante tres a\u00f1os de espera.<\/p>\n<p>Este conjunto est\u00e1 ubicado en la calle 40 con carrera 2 de Yopal, donde con la pavimentaci\u00f3n de la v\u00eda se hicieron evidentes errores de planeaci\u00f3n que han conllevado a la inundaci\u00f3n de un gran n\u00famero de viviendas y grandes p\u00e9rdidas materiales de sus habitantes.<\/p>\n<p>Harold Sierra, vocero de esta comunidad relat\u00f3 a Radio Noticias que desde que estas viviendas fueron entregadas vienen presentando fallas en su estructura y que no se logran corregir por parte de la constructora Manare, que acude a los llamados y manifestaciones prometiendo soluciones que a\u00fan no llegan.<\/p>\n<p>Indic\u00f3 que \u201ccansados de soportar tantas dificultades emprender\u00e1n acciones legales donde los 221 copropietarios demandar\u00e1n por da\u00f1os y perjuicios a la constructora a fin de encontrar alguna salida al problema en el que se ha convertido hacer parte de este proyecto de vivienda\u201d.<\/p>\n<p>Este debate de control pol\u00edtico se llevar\u00e1 a cabo en el recinto del Concejo de Yopal, a partir de las 8 de la ma\u00f1ana con el objetivo de brindar respuestas a la comunidad.<\/p>\n<p>Fuente y Fotograf\u00eda Radio Noticias Casanare<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los graves problemas estructurales del Conjunto Senderos de Manare ser\u00e1n analizados por el Concejo de Yopal, por lo que cit\u00f3 al Gerente de la Inversora Manare, Juan Eduardo Goenaga y al jefe de la Oficina Asesora de Planeaci\u00f3n, Fabio Andr\u00e9s Fajardo Restrepo. El Presidente de la Corporaci\u00f3n, Fabio Su\u00e1rez Caro indic\u00f3 que el debate se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,66],"tags":[3,11,1814,522,238,990],"class_list":["post-5697","post","type-post","status-publish","format-standard","hentry","category-casanare","category-destacadas","tag-casanare","tag-concejo-de-yopal","tag-inversora-manare","tag-proyecto-de-vivienda","tag-radio-noticias-casanare","tag-senderos-de-manare"],"_links":{"self":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/posts\/5697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/comments?post=5697"}],"version-history":[{"count":0,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/posts\/5697\/revisions"}],"wp:attachment":[{"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/media?parent=5697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/categories?post=5697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radionoticiascasanare.com\/inicio\/wp-json\/wp\/v2\/tags?post=5697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}